{"id":923,"count":1,"description":"","link":"https:\/\/blog.blueventures.org\/id\/tag\/local-governance-id\/","name":"local governance","slug":"local-governance-id","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>local governance Arsip - Blue Ventures - Beyond Conservation blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.blueventures.org\/id\/tag\/local-governance-id\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"local governance Arsip - Blue Ventures - Beyond Conservation blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.blueventures.org\/id\/tag\/local-governance-id\/\" \/>\n<meta property=\"og:site_name\" content=\"Blue Ventures - Beyond Conservation blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@blueventures\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.blueventures.org\\\/id\\\/tag\\\/local-governance-id\\\/\",\"url\":\"https:\\\/\\\/blog.blueventures.org\\\/id\\\/tag\\\/local-governance-id\\\/\",\"name\":\"local governance Arsip - Blue Ventures - Beyond Conservation blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.blueventures.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.blueventures.org\\\/id\\\/tag\\\/local-governance-id\\\/#breadcrumb\"},\"inLanguage\":\"id\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.blueventures.org\\\/id\\\/tag\\\/local-governance-id\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.blueventures.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"local governance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.blueventures.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/blog.blueventures.org\\\/en\\\/\",\"name\":\"Blue Ventures - Beyond Conservation blog\",\"description\":\"Voices from the front line of marine conversation\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.blueventures.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"local governance Arsip - Blue Ventures - Beyond Conservation blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.blueventures.org\/id\/tag\/local-governance-id\/","og_locale":"id_ID","og_type":"article","og_title":"local governance Arsip - Blue Ventures - Beyond Conservation blog","og_url":"https:\/\/blog.blueventures.org\/id\/tag\/local-governance-id\/","og_site_name":"Blue Ventures - Beyond Conservation blog","twitter_card":"summary_large_image","twitter_site":"@blueventures","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.blueventures.org\/id\/tag\/local-governance-id\/","url":"https:\/\/blog.blueventures.org\/id\/tag\/local-governance-id\/","name":"local governance Arsip - Blue Ventures - Beyond Conservation blog","isPartOf":{"@id":"https:\/\/blog.blueventures.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/blog.blueventures.org\/id\/tag\/local-governance-id\/#breadcrumb"},"inLanguage":"id"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.blueventures.org\/id\/tag\/local-governance-id\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.blueventures.org\/en\/"},{"@type":"ListItem","position":2,"name":"local governance"}]},{"@type":"WebSite","@id":"https:\/\/blog.blueventures.org\/en\/#website","url":"https:\/\/blog.blueventures.org\/en\/","name":"Blue Ventures - Beyond Conservation blog","description":"Voices from the front line of marine conversation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.blueventures.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"}]}},"_links":{"self":[{"href":"https:\/\/blog.blueventures.org\/id\/wp-json\/wp\/v2\/tags\/923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.blueventures.org\/id\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.blueventures.org\/id\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.blueventures.org\/id\/wp-json\/wp\/v2\/posts?tags=923"},{"href":"https:\/\/blog.blueventures.org\/id\/wp-json\/wp\/v2\/pmb_content?tags=923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}